{"id":8391,"date":"2015-02-16T13:15:26","date_gmt":"2015-02-16T11:15:26","guid":{"rendered":"http:\/\/fr.yeeply.com\/blog\/?p=131"},"modified":"2026-06-26T11:16:57","modified_gmt":"2026-06-26T09:16:57","slug":"jeux-smartphones-unity-3d","status":"publish","type":"post","link":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/","title":{"rendered":"Cr\u00e9er des jeux mobiles avec Unity 3D"},"content":{"rendered":"<p style=\"text-align: justify;\"><a title=\"Site Unity 3D\" href=\"http:\/\/unity3d.com\" target=\"_blank\" rel=\"noopener noreferrer\">Unity 3D <\/a>est l&rsquo;une des plateformes les plus compl\u00e8tes pour <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/creer-un-jeu-android\/\">cr\u00e9er des jeux mobiles<\/a>\u00a0dans le monde. Il permet la cr\u00e9ation de jeux mobiles\u00a0pour plusieurs plates-formes \u00e0 partir d&rsquo;un seul d\u00e9veloppement, y compris les jeux pour console (PlayStation, Xbox et Wii), le bureau (Linux, PC et Mac), navigateur, smartphones\u00a0et tablettes (iOS, Android, Windows Phone et BlackBerry)<\/p>\n<p style=\"text-align: justify;\">C\u2019est peut-\u00eatre la technologie qui connait la plus forte croissance en ce moment, surtout avec la r\u00e9cente mise \u00e0 jour qui facilite le d\u00e9veloppement de <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/creation-de-jeu-mobile-pour-le-sport-la-liga-puzzle\/\">jeux mobiles 2D<\/a>. Sa principale limite est le prix de la licence compl\u00e8te, qui peut atteindre voire m\u00eame d\u00e9passer les <strong>4,500$<\/strong>\u00a0pour une personne. Nous analyserons les raisons justifiant ce prix, les caract\u00e9ristiques de cet environnement, ses limites et son \u00e9tat actuel.<\/p>\n<div style=\"text-align: center;\"><\/div>\n<div><div class=\"bt-proyecto\"><a href=\"https:\/\/yeeply.com\/fr\/developpement-jeux-mobiles\/?rel=FR-BT-proyecto-juego#publish-project\" target=\"_blank\" rel=\"noopener\">VOUS VOULEZ CR\u00c9ER UN JEU MOBILE ? RACONTEZ-NOUS VOTRE PROJET \u270c\ufe0f<\/a><\/div><\/div>\n<h2 style=\"text-align: justify;\"><strong>Environnement de Unity 3D<\/strong><\/h2>\n<p style=\"text-align: justify;\">L&rsquo;\u00e9diteur d\u2019Unity est l&rsquo;un des plus simples et les plus puissants sur le march\u00e9. Il est divis\u00e9 en cinq parties principales:<\/p>\n<ol style=\"text-align: justify;\">\n<li><strong>Navigateur<\/strong>: R\u00e9pertorier tous les \u00e9l\u00e9ments (ou actifs) pour vos projets. Cela vous permet de trier facilement votre demande. Ce sont vos photos, des sc\u00e8nes, des scripts, des audios, prefab et tous les \u00e9l\u00e9ments que vous utiliserez ou pourrez utiliser dans le <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/5-conseils-pour-le-developpement-dapplications-mobiles\/\">d\u00e9veloppement<\/a> de votre jeu ou votre application<\/li>\n<li><strong>Inspecteur<\/strong>: Affiche et d\u00e9finit les propri\u00e9t\u00e9s des \u00e9l\u00e9ments de votre projet. Modifie les valeurs de mani\u00e8re rapide, change les textures en glissant les fichiers depuis l&rsquo;Explorateur, ajoute des scripts, garde les pr\u00e9fabriqu\u00e9s &#8230;<\/li>\n<li><strong>Hi\u00e9rarchie<\/strong>: liste hi\u00e9rarchique des \u00e9l\u00e9ments de votre sc\u00e8ne<\/li>\n<li><strong>Sc\u00e8ne<\/strong>: Conception et mod\u00e8le de votre <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/application-pour-le-sport-football-race\/\">jeu mobile<\/a> complet ou l\u2019\u00e9cran ou une partie de celui. Chaque sc\u00e8ne repr\u00e9sente un niveau ou une section diff\u00e9rente du jeu (couverture, niveau 1, niveau 2, connexion, &#8230;). Il suffit de glisser vos actifs depuis l\u2019explorateur et d\u2019\u00e9diter ses variables depuis l&rsquo;inspecteur<\/li>\n<li>\u00a0<strong>Jeu<\/strong>: Affiche votre jeu selon diff\u00e9rentes r\u00e9solutions. C\u2019est une vue WYSIWYG de votre jeu.<\/li>\n<\/ol>\n<figure id=\"attachment_5701\" aria-describedby=\"caption-attachment-5701\" style=\"width: 748px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"wp-image-5701 size-full\" title=\"capture ecran interface jeu unity 3d \" src=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/6940754613_5db7e5721c_b-1.jpg\" alt=\"capture ecran interface jeu unity 3d \" width=\"748\" height=\"421\" \/><figcaption id=\"caption-attachment-5701\" class=\"wp-caption-text\">Image de <a href=\"https:\/\/www.flickr.com\/photos\/35875713@N08\/\" target=\"_blank\" rel=\"noopener noreferrer\">GuitarMonkey<\/a> via <a href=\"https:\/\/www.flickr.com\/photos\/35875713@N08\/6940754613\/\" target=\"_blank\" rel=\"noopener noreferrer\">Flickr<\/a><\/figcaption><\/figure>\n<h2 style=\"text-align: justify;\"><strong>D\u00e9veloppement des jeux mobiles 3D et 2D<\/strong><\/h2>\n<p style=\"text-align: justify;\">Initialement Unity \u00e9tait un environnement de d\u00e9veloppement pour les jeux 3D. Vous pouviez d\u00e9velopper des environnements et des jeux 2D en ajustant les param\u00e8tres de votre jeu pour simuler le 2D (cam\u00e9ra orthographique, textures plates, etc), mais pour les jeux\u00a0strictement 2D, certains d\u00e9veloppeurs ont opt\u00e9 pour d&rsquo;autres <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/unity-et-cocos2d-developpement-de-jeux-2d\/\">plates-formes telles que Cocos2D<\/a>, a priori mieux adapt\u00e9 \u00e0 la technologie 2D.<\/p>\n<p style=\"text-align: justify;\">Avec ses derni\u00e8res mises \u00e0 jour, Unity simplifie ce processus en permettant des <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/developper-applications-smartphones-avec-corona\/\">d\u00e9veloppements 2D<\/a> de mani\u00e8re beaucoup plus simple, en ajoutant de nouveaux objets et effets pour faciliter le d\u00e9veloppement et la performance de votre jeu, comme les textures 2D, les effets physiques 2D ou des types d\u2019appareil photo sp\u00e9cifiques. Il existe de nombreux exemples de jeux 3D d\u00e9velopp\u00e9s par Unity.<\/p>\n<p style=\"text-align: justify;\">Actuellement, <strong>plus de 500 millions d&rsquo;utilisateurs<\/strong> jouent \u00e0 des jeux d\u00e9velopp\u00e9s par Unity. En r\u00e9alit\u00e9, la plupart des meilleurs jeux smartphones\u00a0pour Android et iOS 3D sont d\u00e9velopp\u00e9s par Unity. En 2D, le pourcentage est beaucoup plus faible, faisant de Cocos 2D le moteur le plus utilis\u00e9 \u00e0 ce jour, principalement parce que Unity n\u2019est pas encore une option solide pour le d\u00e9veloppement de ce type de jeux. Cependant, le principal obstacle d\u2019Unity reste le prix. Cela n&rsquo;a pas emp\u00each\u00e9 certaines entreprises comme <a title=\"Site Rovio\" href=\"http:\/\/www.rovio.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Rovio<\/a>\u00a0de faire\u00a0le choix d\u2019utiliser Unity comme moteur 2D, puisqu\u2019ils ont d\u00e9velopp\u00e9 des jeux mobiles\u00a0\u00e0 succ\u00e8s comme <strong>Bad Piggies<\/strong>.<\/p>\n<h2><p><a href=\"https:\/\/yeeply.com\/fr\/landing\/telechargement-ebook-creation-jeu-mobile\/\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2020\/04\/FR-Te\u0301le\u0301charger-ebook-3-Jeu-Mobile.jpg\" alt=\"Ebook 3 Juego Descarga\" \/><\/a><\/p><\/h2>\n<h2 style=\"text-align: justify;\">Cr\u00e9er des jeux multiplateformes<\/h2>\n<p style=\"text-align: justify;\">Un des plus grands avantages d\u2019Unity est qu&rsquo;il permet le d\u00e9veloppement de <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/creation-de-jeu-smartphone-toxic-origin\/\">jeux mobiles<\/a>\u00a0pour de nombreuses plates-formes avec tr\u00e8s peu de travail suppl\u00e9mentaire. Contrairement \u00e0 d&rsquo;autres technologies, il n\u2019y a presque pas d\u2019ajustement \u00e0 r\u00e9aliser pour adapter des jeux mobiles\u00a0pour iOS ou Android avec Unity, sauf si vous voulez utiliser des fonctionnalit\u00e9s sp\u00e9cifiques \u00e0 l&rsquo;une de ces plateformes. Il est possible de cr\u00e9er des jeux sur presque toutes les plateformes qui existent actuellement:<\/p>\n<h3>Jeux smartphones\u00a0et tablettes<\/h3>\n<p style=\"text-align: justify;\">Unity permet de d\u00e9velopper des jeux mobiles\u00a0pour iOS, Android, Windows Phone 8 et BlackBerry 10. Les licences compl\u00e8tes pour Windows Phone et BlackBerry sont incluses dans la licence de base d\u2019Unity, principalement parce que sinon tr\u00e8s peu de d\u00e9veloppeurs seraient int\u00e9ress\u00e9s par ces appareils. iOS et Android, cependant, n\u00e9cessitent l&rsquo;achat de licences suppl\u00e9mentaires pour achever le d\u00e9veloppement de leurs jeux mobiles.<\/p>\n<p style=\"text-align: justify;\">Pour pouvoir compiler pour chaque dispositif vous avez besoin d\u2019effectuer un travail suppl\u00e9mentaire minime. Pour Android, par exemple, vous devez t\u00e9l\u00e9charger et int\u00e9grer<strong> l\u2019apk de Google<\/strong> pour Android. <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/senregistrer-en-tant-que-developpeur-ios\/\">iOS<\/a> est plus compliqu\u00e9 (comme toujours): Dans un premier temps il n\u00e9cessitera un paiement \u00e0 l&rsquo;\u00e9gard d&rsquo;Apple pour <strong>la licence<\/strong> de d\u00e9veloppeur avec un co\u00fbt actuel de <strong>99 $<\/strong> par an. Vous aurez \u00e9galement besoin d\u2019un Mac pour r\u00e9aliser la version finale des jeux mobiles. Que vous ayez d\u00e9velopp\u00e9 sur Mac ou PC (avec Unity), vous ne poss\u00e8derez pas le fichier final, mais un projet de XCode que vous pouvez ouvrir et compiler avec Mac XCode.<\/p>\n<h3>Navigateur<\/h3>\n<p style=\"text-align: justify;\">Unity permet le d\u00e9veloppement \u00e0 la fois pour navigateur et pour Facebook. Tous les navigateurs modernes vous permettent de jouer \u00e0 ces jeux mobiles: Chrome, Firefox, Internet Explorer et Safari. Actuellement, les jeux smartphones\u00a0cr\u00e9\u00e9s avec Unity (Unity 4.5 dans sa version actuelle) sont jouable avec le webplayer officiel d\u2019Unity, Unity Web Player, qui doit \u00eatre install\u00e9 dans votre navigateur Web pour \u00eatre utilis\u00e9. Avant, Unity exportait les fichiers Flash, mais il a cess\u00e9 de le faire. Dans quelques mois, Unity lancera <strong>Unity 5<\/strong> qui permettra la jouabilit\u00e9 de ses jeux mobiles\u00a0avec HTML 5, ce qui rendra beaucoup plus facile l&rsquo;int\u00e9gration dans les pages Web.<\/p>\n<h3>Bureau<\/h3>\n<p style=\"text-align: justify;\">Vous pouvez aussi compiler pour PC, Mac et Linux. Dans ce cas, le travail suppl\u00e9mentaire effectu\u00e9 est pratiquement inexistant, sauf pour le Mac, qui n\u00e9cessite (de nouveau) quelques \u00e9tapes suppl\u00e9mentaires.<\/p>\n<h3>Console<\/h3>\n<p style=\"text-align: justify;\">Unity a annonc\u00e9 r\u00e9cemment qu&rsquo;il sera possible de d\u00e9velopper gratuitement des jeux sans co\u00fbt additionel pour PS3 \/ PS4, Wii U et Xbox 360. Toutefois, il n\u2019est pas toujours int\u00e9ressant de cr\u00e9er des jeux pour ces consoles, du moins pour les entreprises et petites \u00e9quipes. Unity n\u2019a pas besoin de licences suppl\u00e9mentaires mais vous aurez besoin d&rsquo;\u00e9quipes de d\u00e9veloppement pour les diff\u00e9rentes platesformes qui doivent \u00eatre fournis par Sony, Nintendo et Microsoft, respectivement.<\/p>\n<figure id=\"attachment_5700\" aria-describedby=\"caption-attachment-5700\" style=\"width: 748px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-5700 size-full\" title=\"illustration jeu cascadeur\" src=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/31917668324_3262d04d89_k-1.jpg\" alt=\"illustration jeu cascadeur\" width=\"748\" height=\"935\" \/><figcaption id=\"caption-attachment-5700\" class=\"wp-caption-text\">Image de <a href=\"https:\/\/www.flickr.com\/photos\/cinematicaptures\/\" target=\"_blank\" rel=\"noopener noreferrer\">Cinematic Captures<\/a> via <a href=\"https:\/\/www.flickr.com\/photos\/cinematicaptures\/31917668324\/\" target=\"_blank\" rel=\"noopener noreferrer\">Flickr<\/a><\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Actuellement, les d\u00e9veloppements pour console r\u00e9alis\u00e9s avec Unity ont les plus <strong>petits budgets,<\/strong> se concentrant sur les t\u00e9l\u00e9chargements dans les stores des trois consoles. Les premiers jeux offerts par Sony pour les utilisateurs premium de la PS4 ont \u00e9t\u00e9 faits avec Unity 3D. Les jeux les plus puissants de ces consoles utilisent d&rsquo;autres moteurs tel que Unreal.<\/p>\n<h2 style=\"text-align: justify;\"><strong>Tarifs<\/strong><\/h2>\n<p style=\"text-align: justify;\">C\u2019est l&rsquo;obstacle principal\u00a0<a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/ce-que-vous-devez-savoir-sur-un-developpeur-dapplications\/\">pour les d\u00e9veloppeurs<\/a>: le prix des licences. Un d\u00e9veloppeur peut commencer avec la licence libre, mais il sera limit\u00e9. Le projet d\u00e9velopp\u00e9 devra n\u00e9cessairement inclure le logo d\u2019Unity pendant le temps de charge de vos jeux mobiles\u00a0et ne pourra \u00eatre utilis\u00e9 que si le chiffre d&rsquo;affaires total de votre entreprise ne d\u00e9passe pas $ 100 000 par an.<\/p>\n<p style=\"text-align: justify;\">Le prix de la licence d\u2019<strong>Unity Pro est de 1500 $<\/strong> par personne, plus les taxes. Elle permet l&rsquo;utilisation de toutes les fonctionnalit\u00e9s d\u2019Unity Pro sur deux ordinateurs (pour un m\u00eame compte utilisateur). Les principales am\u00e9liorations sont les textures et les performances 3D. Les jeux mobiles\u00a0simples, et en particulier les jeux 2D ne devraient pas avoir besoin de ces fonctionnalit\u00e9s.<\/p>\n<p style=\"text-align: justify;\">Les licences Pro pour Windows Phone et BlackBerry sont <strong>inclus dans Unity Pro<\/strong>, mais pas pour Android et iOS. Les licences de iOS\u00a0Pro et Android Pro sont co\u00fbtent\u00a0$ 1,500 par personne (excluant les taxes). Elles sont obligatoires, par exemple, pour l&rsquo;utilisation de .Net Sockets, et elles sont n\u00e9cessaires pour certaines applications\u00a0multi-joueurs en temps r\u00e9el. La somme de ces <a href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-applications-mobiles\/avez-vous-une-idee-de-combien-coute-le-developpement-de-votre-application-besoin-dun-budget\/\">co\u00fbts<\/a> est le principal obstacle \u00e0 l&rsquo;utilisation de la technologie Unity, bien qu&rsquo;ils compensent largement le temps de d\u00e9veloppement \u00e9conomis\u00e9 ainsi que la qualit\u00e9 du produit.<\/p>\n<h2><strong>Asset Store jeux\u00a0mobiles<\/strong><\/h2>\n<figure id=\"attachment_5699\" aria-describedby=\"caption-attachment-5699\" style=\"width: 748px\" class=\"wp-caption aligncenter\"><img decoding=\"async\" class=\"wp-image-5699 size-full\" title=\"page accueil Asset store Unity 3d\" src=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/Captura-de-pantalla-2018-08-20-a-las-9.28.04.jpg\" alt=\"page accueil Asset store Unity 3d\" width=\"748\" height=\"360\" \/><figcaption id=\"caption-attachment-5699\" class=\"wp-caption-text\">Image de Yeeply<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><strong>La force d&rsquo;Unity\u00a0va bien\u00a0au del\u00e0<\/strong> des\u00a0autres technologies populaires pour le d\u00e9veloppement de jeux mobiles\u00a0tels\u00a0que Cocos2D, Flash ou Marmalade. Cette qualit\u00e9 se voit renforc\u00e9e par les \u00ab\u00a0assets\u00a0\u00bb qui sont offerts gratuitement\u00a0ou vendus dans l&rsquo;Asset Store.<\/p>\n<p style=\"text-align: justify;\">Certains, comme Ngui, am\u00e9liorent et facilitent votre d\u00e9veloppement de jeux mobiles\u00a0tel que le ferait\u00a0jQuery avec un d\u00e9veloppement en \u00a0Javascript. Dans le magasin d&rsquo;Unity, vous pouvez trouver des mod\u00e8les 3D pr\u00eats \u00e0 l&#8217;emploi, des interfaces utilisateurs, exportateurs \/ importateurs de Photoshop, des moteurs de\u00a0 physique, des exemples de jeux mobiles,\u00a0des scripts\u00a0de toutes sortes, des animations, des syst\u00e8mes de particules, des extensions pour votre \u00e9diteur, <span class=\"hps\">et plus encore<\/span>.<\/p>\n<p style=\"margin: 0cm 0cm 10pt; text-align: justify;\">Nous vous recommandons de bien \u00e9tudier ce qu&rsquo;offre Unity, car\u00a0il pourrait en outre r\u00e9duire le temps de d\u00e9veloppement <strong>de votre projet.<\/strong><\/p>\n<p><a href=\"https:\/\/yeeply.com\/fr\/developpement-jeux-mobiles\/?rel=FR-BP-proyecto-juego#publish-project\" target=\"_blank\" rel=\"noopener\"><img decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2020\/04\/FR-CTA-projet-jeu-mobile.jpg\" alt=\"Proyecto Juego\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Unity 3D est l&rsquo;une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles\u00a0dans le monde. Il permet la cr\u00e9ation de jeux mobiles\u00a0pour plusieurs plates-formes &#8230;<\/p>\n","protected":false},"author":2,"featured_media":8109,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[303],"tags":[],"class_list":["post-8391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-developpement-jeux-mobiles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Comment cr\u00e9er des jeux mobiles avec Unity 3D ?<\/title>\n<meta name=\"description\" content=\"Unity 3D est l&#039;une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comment cr\u00e9er des jeux mobiles avec Unity 3D ?\" \/>\n<meta property=\"og:description\" content=\"Unity 3D est l&#039;une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/\" \/>\n<meta property=\"og:site_name\" content=\"Yeeply\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/YeeplyMobile\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-16T11:15:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-26T09:16:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"748\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Yeeply\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Yeeply_EN\" \/>\n<meta name=\"twitter:site\" content=\"@Yeeply_EN\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Yeeply\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/\"},\"author\":{\"name\":\"Yeeply\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#\\\/schema\\\/person\\\/c7927839158c47143448f3bcdaf7cc14\"},\"headline\":\"Cr\u00e9er des jeux mobiles avec Unity 3D\",\"datePublished\":\"2015-02-16T11:15:26+00:00\",\"dateModified\":\"2026-06-26T09:16:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/\"},\"wordCount\":1596,\"publisher\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/36737920142_f682348373_b-1.jpg\",\"articleSection\":[\"Jeux\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/\",\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/\",\"name\":\"Comment cr\u00e9er des jeux mobiles avec Unity 3D ?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/36737920142_f682348373_b-1.jpg\",\"datePublished\":\"2015-02-16T11:15:26+00:00\",\"dateModified\":\"2026-06-26T09:16:57+00:00\",\"description\":\"Unity 3D est l'une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/36737920142_f682348373_b-1.jpg\",\"contentUrl\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/36737920142_f682348373_b-1.jpg\",\"width\":748,\"height\":421,\"caption\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/blog\\\/developpement-jeux-mobiles\\\/jeux-smartphones-unity-3d\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cr\u00e9er des jeux mobiles avec Unity 3D\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/\",\"name\":\"Yeeply\",\"description\":\"A platform for the development of digital projects\",\"publisher\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#organization\",\"name\":\"Yeeply\",\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_yeeply_black@2x.png\",\"contentUrl\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_yeeply_black@2x.png\",\"width\":360,\"height\":120,\"caption\":\"Yeeply\"},\"image\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/YeeplyMobile\\\/\",\"https:\\\/\\\/x.com\\\/Yeeply_EN\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yeeply\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/#\\\/schema\\\/person\\\/c7927839158c47143448f3bcdaf7cc14\",\"name\":\"Yeeply\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g\",\"caption\":\"Yeeply\"},\"url\":\"https:\\\/\\\/yeeply.com\\\/fr\\\/author\\\/yeeply\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comment cr\u00e9er des jeux mobiles avec Unity 3D ?","description":"Unity 3D est l'une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/","og_locale":"fr_FR","og_type":"article","og_title":"Comment cr\u00e9er des jeux mobiles avec Unity 3D ?","og_description":"Unity 3D est l'une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.","og_url":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/","og_site_name":"Yeeply","article_publisher":"https:\/\/www.facebook.com\/YeeplyMobile\/","article_published_time":"2015-02-16T11:15:26+00:00","article_modified_time":"2026-06-26T09:16:57+00:00","og_image":[{"width":748,"height":421,"url":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg","type":"image\/jpeg"}],"author":"Yeeply","twitter_card":"summary_large_image","twitter_creator":"@Yeeply_EN","twitter_site":"@Yeeply_EN","twitter_misc":{"\u00c9crit par":"Yeeply","Dur\u00e9e de lecture estim\u00e9e":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#article","isPartOf":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/"},"author":{"name":"Yeeply","@id":"https:\/\/yeeply.com\/fr\/#\/schema\/person\/c7927839158c47143448f3bcdaf7cc14"},"headline":"Cr\u00e9er des jeux mobiles avec Unity 3D","datePublished":"2015-02-16T11:15:26+00:00","dateModified":"2026-06-26T09:16:57+00:00","mainEntityOfPage":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/"},"wordCount":1596,"publisher":{"@id":"https:\/\/yeeply.com\/fr\/#organization"},"image":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg","articleSection":["Jeux"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/","url":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/","name":"Comment cr\u00e9er des jeux mobiles avec Unity 3D ?","isPartOf":{"@id":"https:\/\/yeeply.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#primaryimage"},"image":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#primaryimage"},"thumbnailUrl":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg","datePublished":"2015-02-16T11:15:26+00:00","dateModified":"2026-06-26T09:16:57+00:00","description":"Unity 3D est l'une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles. Elle simplifie la cr\u00e9ation multiplateforme.","breadcrumb":{"@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#primaryimage","url":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg","contentUrl":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg","width":748,"height":421,"caption":""},{"@type":"BreadcrumbList","@id":"https:\/\/yeeply.com\/fr\/blog\/developpement-jeux-mobiles\/jeux-smartphones-unity-3d\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yeeply.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cr\u00e9er des jeux mobiles avec Unity 3D"}]},{"@type":"WebSite","@id":"https:\/\/yeeply.com\/fr\/#website","url":"https:\/\/yeeply.com\/fr\/","name":"Yeeply","description":"A platform for the development of digital projects","publisher":{"@id":"https:\/\/yeeply.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yeeply.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/yeeply.com\/fr\/#organization","name":"Yeeply","url":"https:\/\/yeeply.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/yeeply.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2019\/05\/logo_yeeply_black@2x.png","contentUrl":"https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2019\/05\/logo_yeeply_black@2x.png","width":360,"height":120,"caption":"Yeeply"},"image":{"@id":"https:\/\/yeeply.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/YeeplyMobile\/","https:\/\/x.com\/Yeeply_EN","https:\/\/www.linkedin.com\/company\/yeeply"]},{"@type":"Person","@id":"https:\/\/yeeply.com\/fr\/#\/schema\/person\/c7927839158c47143448f3bcdaf7cc14","name":"Yeeply","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f13a8a35567805732422f808376743c5cc1b8918b3dd8f2da231a8306df22006?s=96&d=mm&r=g","caption":"Yeeply"},"url":"https:\/\/yeeply.com\/fr\/author\/yeeply\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",748,421,false],"thumbnail":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1-150x150.jpg",150,150,true],"medium":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1-300x169.jpg",300,169,true],"medium_large":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",640,360,false],"large":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",640,360,false],"1536x1536":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",748,421,false],"2048x2048":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",748,421,false],"gform-image-choice-sm":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",300,169,false],"gform-image-choice-md":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",400,225,false],"gform-image-choice-lg":["https:\/\/yeeply.com\/fr\/wp-content\/uploads\/2015\/02\/36737920142_f682348373_b-1.jpg",600,338,false]},"uagb_author_info":{"display_name":"Yeeply","author_link":"https:\/\/yeeply.com\/fr\/author\/yeeply\/"},"uagb_comment_info":0,"uagb_excerpt":"Unity 3D est l&rsquo;une des plateformes les plus compl\u00e8tes pour cr\u00e9er des jeux mobiles\u00a0dans le monde. Il permet la cr\u00e9ation de jeux mobiles\u00a0pour plusieurs plates-formes ...","_links":{"self":[{"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/posts\/8391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/comments?post=8391"}],"version-history":[{"count":10,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/posts\/8391\/revisions"}],"predecessor-version":[{"id":17417,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/posts\/8391\/revisions\/17417"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/media\/8109"}],"wp:attachment":[{"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/media?parent=8391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/categories?post=8391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yeeply.com\/fr\/wp-json\/wp\/v2\/tags?post=8391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}