{"id":5917,"date":"2024-07-12T12:34:44","date_gmt":"2024-07-12T10:34:44","guid":{"rendered":"https:\/\/en.yeeply.com\/?page_id=5917"},"modified":"2024-07-12T12:34:49","modified_gmt":"2024-07-12T10:34:49","slug":"faq","status":"publish","type":"page","link":"https:\/\/yeeply.com\/de\/faq\/","title":{"rendered":"FAQ \u2013 H\u00e4ufige Fragen \u2013 Yeeply"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light page-hero\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#f3f5f9\"><\/span><img fetchpriority=\"high\" decoding=\"async\" width=\"2880\" height=\"1200\" class=\"wp-block-cover__image-background wp-image-5918\" alt=\"\" src=\"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg\" style=\"object-position:50% 50%\" data-object-fit=\"cover\" data-object-position=\"50% 50%\" srcset=\"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg 2880w, https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x-300x125.png 300w, https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x-768x320-1.jpg 768w, https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x-1024x427-1.jpg 1024w\" sizes=\"(max-width: 2880px) 100vw, 2880px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h1 class=\"wp-block-heading has-text-align-left\">FAQ<\/h1>\n\n\n\n<p><div class=\"faq-search\">\n<img decoding=\"async\" src=\"\/wp-content\/uploads\/2019\/05\/search-icon.svg\">\n<input placeholder=\"Suchen...\" id=\"faq-search-input\" type=\"text\">\n<img decoding=\"async\" class=\"search-clear\" src=\"\/wp-content\/uploads\/2019\/05\/ico_cancel_search.svg\">\n<\/div><\/p>\n<\/div><\/div>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-f17d0957-e691-496c-921e-77035b7f4c53 section-full section-main-faq\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-d2c4f82a-1bfd-4073-94a0-19178f690d57\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">\u00dcber Yeeply<\/h2>\n\n\n\n<p class=\"has-text-align-center no-results\">No results found<\/p>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"a39164087dda9e37425b69f071157047\">\n<div class=\"wp-block-toolset-views-view-editor wpv-gutenberg-view-wrapper-6187\">\n\n\n<div id=\"wpv-view-layout-6187\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-6187\" data-viewnumber=\"6187\" data-pagination=\"{&quot;id&quot;:&quot;6187&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6187&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6187\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Was ist Yeeply?<\/h3>\n    <p>Wir sind ein Marktplatz, der Sie <strong>mit dem besten Team f\u00fcr Ihr digitales Projekt verbindet<\/strong> &#8211; ein schneller und sicherer Weg, um alle technischen Dienstleistungen, die Sie ben\u00f6tigen, auszulagern<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Welche Art von Projekten f\u00fchren Sie durch?<\/h3>\n    <p>In den letzten Jahren haben wir mehr als <strong>1000 Projekte<\/strong> f\u00fcr eine Vielzahl an Kunden weltweit durchgef\u00fchrt.<\/p>\n<p>Dies sind einige Bespiele der Dienste, die unsere Kunden ausgelagert haben:<\/p>\n<ul>\n<li>Digitale Transformation<\/li>\n<li>Mobile App Entwicklung<\/li>\n<li>Website Entwicklung<\/li>\n<li>Software Entwicklung<\/li>\n<li>Design Thinking<\/li>\n<li>Digitales Marketing (ASO, SEM, SEO, etc.)<\/li>\n<li>UX, UI und Grafikdesign<\/li>\n<\/ul>\n<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wer sind Ihre Kunden?<\/h3>\n    <p>Jedes Projekt, das wir bei der Umsetzung unterst\u00fctzen, ist einzigartig; genau wie unsere Kunden. Wir arbeiten mit allen Unternehmensarten &#8211; von <strong>Startups<\/strong> zu <strong>KMUs<\/strong>, <strong>gro\u00dfen Unternehmen<\/strong>, <strong>Agenturen<\/strong> und mehr. Das Kerngesch\u00e4ft, die Unternehmensgr\u00f6\u00dfe oder der Sektor spielen keine Rolle. Sofern der Kunde ein seri\u00f6ses Projekt und ein f\u00fcr die Umsetzung verf\u00fcgbares Budget hat, k\u00f6nnen wir mit der Zusammenarbeit beginnen.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wer sind die Experten von Yeeply und wo befinden Sie sich?<\/h3>\n    <p>Unsere zertifizierten Experten sind Partner, Entwicklungsunternehmen, Marketing Agenturen und mehr. F\u00fcr Ihr Projekt k\u00f6nnen Sie dennoch entweder ein bereits existierendes Team ben\u00f6tigen, oder eines, das wir auf der Grundlage der ben\u00f6tigten Profile zusammenstellen.<\/p>\n<p>Sie k\u00f6nnen je nach Ihren Bed\u00fcrfnissen verschiedene Teams zusammenstellen:<\/p>\n<ul>\n<li><strong>Expertenteam<\/strong>. &gt; Ein Team, das auf eine bestimmte Dienstleistung spezialisiert ist und das tut, was es am besten kann. Zum Beispiel die Entwicklung von Android-Apps.<\/li>\n<li><strong>Multidisziplin\u00e4res Team<\/strong>. &gt; Ein Team mit den Kompetenzen, mehrere Dienste abzudecken. Zum Beispiel das UI, UX und die Entwicklung einer Website.<\/li>\n<li><strong>Eine Mischung aus Expertenteams<\/strong> &gt; Eine Fusion von Expertenteams, die Ihr Projekt von A-Z abdecken. Die perfekte L\u00f6sung f\u00fcr digitale Transformationsprojekte.<\/li>\n<\/ul>\n<p>Wir arbeiten nur mit den <strong>weltbesten Fachleuten<\/strong> zusammen. Das bedeutet auch, dass unsere Experten auf der ganzen Welt zu finden sind und immer ein Team zur Verf\u00fcgung steht, das mit der Arbeit an Ihrem Projekt beginnen kann.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Was genau hei\u00dft &#8222;zertifizierte&#8220; Experten?<\/h3>\n    <p>Wenn wir \u00fcber zertifizierte Experten sprechen, beziehen wir uns auf <strong>Experten, die unseren anspruchsvollen Zertifizierungsprozess absolviert haben<\/strong>. Die einzelnen Schritte bestehen aus einem Interview, einer \u00dcberpr\u00fcfung der Referenzen, \u00dcberpr\u00fcfung der technischen F\u00e4higkeiten usw. Am Ende werden nur 1% der bei uns eingehenden Bewerbungen bewilligt.<\/p>\n<p>Zudem ist dies auch ein evolution\u00e4rer Prozess f\u00fcr unsere Teams, um unser Vertrauen zu gewinnen. Wenn wir die Zusammenarbeit mit Ihnen aufnehmen, erh\u00f6hen wir die Anzahl der Projekte und Verantwortlichkeiten, sobald Sie Ihre <strong>Kompetenz unter Beweis gestellt haben<\/strong>.<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-87233e66-1953-4e8d-9299-f823c23e30dc\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">Bez\u00fcglich unseres Dienstes<\/h2>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"209a0dc90d7e954bfea3daadad8af0fb\">\n<div class=\"wp-block-toolset-views-view-editor \">\n\n\n<div id=\"wpv-view-layout-6193\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-6193\" data-viewnumber=\"6193\" data-pagination=\"{&quot;id&quot;:&quot;6193&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6193&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6193\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Mein Projekt oder meine Idee ist noch nicht vollst\u00e4ndig definiert. Kann Yeeply mir helfen?<\/h3>\n    <p>Ja, wir bieten auch <strong>Beratungsdienste<\/strong> an, um Sie in den fr\u00fchen Phasen des Projekts zu unterst\u00fctzen. H\u00e4ufig stellen unsere Kunden im Gespr\u00e4ch \u00fcber Ihr Projekt mit uns fest, dass Sie noch nicht \u00fcber alle Details nachgedacht haben. Die Inanspruchnahme von Beratungsdiensten wird Ihnen helfen, <strong>Ihr Projekt zum Laufen zu bringen<\/strong>.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Was ist der Unterschied zwischen der Beauftragung von Yeeply und dem direkten Kontakt mit einem Team?<\/h3>\n    <p>Wir erleichtern und sichern die Suche nach dem idealen Team f\u00fcr Ihr Projekt:<\/p>\n<ul>\n<li>Aufgrund<strong> unserer<\/strong> <strong>Erfahrung<\/strong> wissen wir genau, welche Profile Sie f\u00fcr die Durchf\u00fchrung Ihres Projekts ben\u00f6tigen.<\/li>\n<li>Sie sparen Zeit bei der Suche nach dem <strong>Traumteam mit Erfahrung in \u00e4hnlichen Projekten wie Ihrem<\/strong>.<\/li>\n<li><strong>Professionalit\u00e4t und Qualit\u00e4t<\/strong> sind garantiert, da alle unsere Teams und Fachleute zertifiziert sind.<\/li>\n<li>Viele Projekte erfordern <strong>Unterst\u00fctzung in verschiedenen Bereichen<\/strong>, mit uns k\u00f6nnen Sie alle Ihre Outsourcing-Bed\u00fcrfnisse an einem Ort abdecken.<\/li>\n<li>Wir bieten <strong>individuelle L\u00f6sungen<\/strong> f\u00fcr jede Art von Unternehmen. Dabei werden Ihre Bed\u00fcrfnisse, der Umfang des Projekts, das Budget usw. ber\u00fccksichtigt.<\/li>\n<li>Wenn das eingesetzte <strong>Team oder der Vorschlag<\/strong> nicht Ihren Erwartungen entspricht, k\u00f6nnen wir Sie mit einem anderen Team in Kontakt bringen.<\/li>\n<li>Wir setzen uns daf\u00fcr ein, <strong>dass alles wie geplant l\u00e4uft<\/strong>; die Chance, dass etwas schief geht, ist wirklich gering.<\/li>\n<\/ul>\n<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Kann ich mein Projekt \u00fcber Ihre Plattform verwalten?<\/h3>\n    <p>Ja, unsere Plattform erm\u00f6glicht es Ihnen, Ihre Kommunikation und den Fortschritt Ihres Projektes zu zentralisieren. Sie k\u00f6nnen die Arbeit problemlos <strong>\u00fcberwachen und \u00fcberpr\u00fcfen<\/strong> und werden benachrichtigt, wenn Meilensteine erreicht wurden.<\/p>\n<p>Selbstverst\u00e4ndlich verstehen wir es, wenn Unternehmen oder Agenturen es vorziehen, Ihre eigenen <strong>Management- oder Kommunikations-Tools<\/strong> einzusetzen. In diesem Fall k\u00f6nnen Sie jede Alternative nutzen, die Sie zur Steuerung Ihres Projekts vorziehen.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Bieten Sie Instandhaltungsdienste f\u00fcr abgeschlossene Projekte?<\/h3>\n    <p>Ja, viele Kunden arbeiten weiterhin mit demselben Team zusammen, um ein <strong>kontinuierliches Wachstum und Verbesserungen<\/strong> zu erreichen. Bedenken Sie Wartungen, Software-Aktualisierungen, neue Funktionen, Designanpassung usw.<\/p>\n<p>In der Regel ber\u00fccksichtigen wir jedoch von Anfang an einige Wartungsstunden. Dadurch vermeiden wir, dass Sie nach der Lieferung des Projekts mit unerwarteten Kosten \u00fcberrascht werden. Diese Stunden beinhalten <strong>Anpassungen und Fehlerkorrekturen<\/strong>. Falls Sie neue Funktionen hinzuf\u00fcgen oder komplexe technische \u00c4nderungen vornehmen m\u00f6chten, m\u00fcssen Sie f\u00fcr den Mehraufwand aufkommen.<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-8096100d-76ee-43a9-91aa-779a7ea0c01d\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">Preise <\/h2>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"515ecda421924f41fc5377e133a61692\">\n<div class=\"wp-block-toolset-views-view-editor wpv-gutenberg-view-wrapper-6189\">\n\n\n<div id=\"wpv-view-layout-6189\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-6189\" data-viewnumber=\"6189\" data-pagination=\"{&quot;id&quot;:&quot;6189&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6189&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6189\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>K\u00f6nnen Sie mir mehr zu den Kosten meines Projekts sagen?<\/h3>\n    <p>Ja, k\u00f6nnen wir. Zun\u00e4chst sollten Sie uns ein bisschen mehr \u00fcber Ihr Projekt erz\u00e4hlen. Dies k\u00f6nnen Sie <span class=\"ypOpenPublishProjectModal\"><a href=\"https:\/\/yeeply.com\/de\/faq\/#publish-project\" rel=\"noopener noreferrer\" target=\"_blank\">\u00fcber dieses Formular<\/a><\/span> erledigen. Danach setzen wir uns mit Ihnen in Verbindung, um die restlichen Details zu besprechen, bevor wir Ihnen ein Angebot zukommen lassen.<\/p>\n<p>Die Beantragung eines Angebots ist <strong>unverbindlich<\/strong>. Wenn es Ihren Erwartungen entspricht, k\u00f6nnen Sie es annehmen, und wir beginnen mit der Arbeit an Ihrem Projekt!<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wo kann ich die Preise f\u00fcr die jeweiligen Projektarten finden?<\/h3>\n    <p>Es gibt einen Grund, weshalb wir keine Preisseite auf unserer Website haben. Es liegt einfach daran, dass <strong>die Kosten f\u00fcr ein Projekt von vielen Faktoren abh\u00e4ngen<\/strong>. Denken Sie an den Schwerpunkt Ihres Projekts, die Art der Dienstleistung(en), die Sie auslagern m\u00f6chten, die erforderlichen Profile, Ihr Budget usw.<\/p>\n<p>Um die ungef\u00e4hren Kosten Ihres Projekts zu ermitteln, ben\u00f6tigen wir dar\u00fcber so viele Informationen wie m\u00f6glich. Dies ist nat\u00fcrlich 100% vertraulich und <strong>an keine Bedingungen gekn\u00fcpft<\/strong>.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wie k\u00f6nnen Sie so ein attraktives Preis-Leistungs-Verh\u00e4ltnis anbieten?<\/h3>\n    <p>Eine qualitativ hochwertige Dienstleistung bedeutet nicht unbedingt, dass sie auch die teuerste Option ist. Wir werden unser Bestes geben, um eine <strong>L\u00f6sung anzubieten, die Ihrem Budget und Ihren Bed\u00fcrfnissen entspricht<\/strong>.<\/p>\n<p>Dies ist durch<strong> starke Partnerschaften<\/strong> mit unseren zertifizierten Fachleuten m\u00f6glich und weil alles online ist. Einerseits gibt uns die kontinuierliche Zusammenarbeit mit Partnern die M\u00f6glichkeit zu verhandeln. Und andererseits <strong>sind<\/strong> <strong>unsere zertifizierten Fachleute geografisch verteilt<\/strong>, was beispielsweise zu einem anderen Stundenpreis f\u00fchrt.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Arbeiten Sie mit Stundens\u00e4tzen oder mit Festpreisen?<\/h3>\n    <p>Beides. Sie k\u00f6nnen unsere Fachleute auf der Grundlage eines <strong>Festpreismodells<\/strong> einstellen oder Sie k\u00f6nnen einen <strong>Vertrag auf Zeit- und Materialbasis<\/strong> w\u00e4hlen. Es h\u00e4ngt alles von Ihren W\u00fcnschen ab und davon, was am besten zu Ihrem Projekt passt. Wir helfen Ihnen, die Einstellungsbedingungen zu definieren, mit denen Sie sich am wohlsten f\u00fchlen.<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-26168bc7-1465-44d0-b56a-08fb958bcea8\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">Vertrag &amp; Zahlungen<\/h2>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"224007f478ccba5ffe756c2217314f96\">\n<div class=\"wp-block-toolset-views-view-editor wpv-gutenberg-view-wrapper-6191\">\n\n\n<div id=\"wpv-view-layout-6191\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-6191\" data-viewnumber=\"6191\" data-pagination=\"{&quot;id&quot;:&quot;6191&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6191&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=6191\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Mit wem werde ich einen Vertrag unterschreiben, mit dem Team, das ich engagiere oder mit Yeeply?<\/h3>\n    <p>Sie werden einen Vertrag mit Yeeply unterzeichnen &#8211; wir sind daf\u00fcr verantwortlich, dass Ihr Projekt unter optimalen Bedingungen entwickelt wird. Wenn w\u00e4hrend des Projekts etwas nicht wie geplant l\u00e4uft, k\u00fcmmern wir uns darum, es zu korrigieren. Sie k\u00f6nnen immer <strong>auf unsere Unterst\u00fctzung z\u00e4hlen, wann immer sie gebraucht wird<\/strong>.<\/p>\n<p>Das Team hingegen wird gleichzeitig eine Vereinbarung mit Yeeply unterzeichnen, um an Ihrem Projekt zu arbeiten.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Bieten Sie eine Art von Garantie an?<\/h3>\n    <p>Ja, wir bieten unseren Kunden eine <strong>6-monatige Garantie<\/strong>. Das bedeutet, dass wir f\u00fcr die Behebung jeglicher Art von Fehlern oder technischen Vorf\u00e4llen im Zusammenhang mit den im Vertrag definierten Funktionalit\u00e4ten verantwortlich sind.<\/p>\n<p>Trotzdem ist der Grad der Zufriedenheit unserer Kunden sehr hoch. Von allen Projekten, an deren Durchf\u00fchrung wir in all den Jahren mitgewirkt haben, <strong>konnten wir die Erwartungen von 94% unserer Kunden erf\u00fcllen<\/strong>.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wann entstehen die ersten (und weiteren) Kosten?<\/h3>\n    <p>Wir ben\u00f6tigen immer eine <strong>Anzahlung<\/strong>, um Ihr Projekt in Gang zu bringen. Der Prozentsatz dieser ersten Zahlung h\u00e4ngt von der Vereinbarung ab, schwankt aber normalerweise zwischen 30% und 50% der Gesamtkosten. Dies erm\u00f6glicht es uns, die notwendigen Ressourcen f\u00fcr das Projekt bereitzustellen.<\/p>\n<p>Die Restsumme wird gezahlt, wenn die <strong>vordefinierten Meilensteine<\/strong> erreicht sind. Diese Anzahl kann je nach Projekt variieren.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Welche Zahlungsmethoden bieten Sie an?<\/h3>\n    <p>Yeeply akzeptiert PayPal, TransferWise und regul\u00e4re Bank\u00fcberweisungen als m\u00f6gliche Zahlungsmethoden.<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-13a61a40-4756-4b46-bf21-5ab847008a28\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">Datenschutz &amp; Vertraulichkeit<\/h2>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"eb30a4c2dcd3a60820c0ecd26a883828\">\n<div class=\"wp-block-toolset-views-view-editor wpv-gutenberg-view-wrapper-12093\">\n\n\n<div id=\"wpv-view-layout-12093\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-12093\" data-viewnumber=\"12093\" data-pagination=\"{&quot;id&quot;:&quot;12093&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=12093&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=12093\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Ich m\u00f6chte meine Idee sch\u00fctzen, kann ich ein NDA mit Yeeply unterzeichnen?<\/h3>\n    <p>Ja, wenn Sie es w\u00fcnschen, k\u00f6nnen wir Ihnen eine <strong>Geheimhaltungsvereinbarung<\/strong> zwischen uns (Yeeply) und Ihnen (dem Kunden) anbieten. Wir stellen allen Kunden, die dies w\u00fcnschen und die ein echtes Interesse an der Durchf\u00fchrung eines Projekts mit uns gezeigt haben, eine NDA zur Verf\u00fcgung.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Ist meine Idee gesch\u00fctzt, wenn ich mit einem Team spreche, mit dem ich eventuell zusammenarbeiten m\u00f6chte?<\/h3>\n    <p>Ja. Nachdem wir Ihnen ein Team zugewiesen haben, k\u00f6nnen Sie die Einzelheiten Ihres Projekts <strong>direkt mit diesem Team besprechen<\/strong>. Sie brauchen sich keine Sorgen um die Sicherheit Ihrer Idee zu machen, da sie f\u00fcr alle Yeeply-Projekte eine <strong>Vertraulichkeitserkl\u00e4rung<\/strong> unterschrieben haben.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wem geh\u00f6rt der Quellcode, wenn mein Projekt abgeschlossen ist?<\/h3>\n    <p>Am Ende jedes Projekts wird der Quellcode <strong>an den Kunden \u00fcbergeben<\/strong> &#8211; was ihn auch zum alleinigen Eigent\u00fcmer macht. Nur in Ausnahmef\u00e4llen kann der Quellcode vom Experten wiederverwendet werden, um die Kosten f\u00fcr ein anderes Projekt zu senken. In diesem Fall m\u00fcssen die <strong>Bedingungen der gemeinsamen Nutzung des Quellcodes<\/strong> dem Kunden vorher mitgeteilt werden und sollten im Vertrag erw\u00e4hnt werden<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-8d3480d8-ba40-490c-bbbf-5a6eef9bcb5e\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<h2 class=\"wp-block-heading has-text-align-center\">Zertifizierter Experte werden<\/h2>\n\n\n<div class=\"wpv-view-output\" data-toolset-views-view-editor=\"89f0c299f84ebb54ac453690ecdfef11\">\n<div class=\"wp-block-toolset-views-view-editor wpv-gutenberg-view-wrapper-12099\">\n\n\n<div id=\"wpv-view-layout-12099\" class=\"js-wpv-view-layout js-wpv-layout-responsive js-wpv-view-layout-12099\" data-viewnumber=\"12099\" data-pagination=\"{&quot;id&quot;:&quot;12099&quot;,&quot;query&quot;:&quot;normal&quot;,&quot;type&quot;:&quot;disabled&quot;,&quot;effect&quot;:&quot;fade&quot;,&quot;duration&quot;:500,&quot;speed&quot;:5,&quot;pause_on_hover&quot;:&quot;disabled&quot;,&quot;stop_rollover&quot;:&quot;false&quot;,&quot;cache_pages&quot;:&quot;enabled&quot;,&quot;preload_images&quot;:&quot;enabled&quot;,&quot;preload_pages&quot;:&quot;enabled&quot;,&quot;preload_reach&quot;:1,&quot;spinner&quot;:&quot;builtin&quot;,&quot;spinner_image&quot;:&quot;https:\/\/www.yeeply.com\/en\/wp-content\/plugins\/wp-views\/embedded\/res\/img\/ajax-loader.gif&quot;,&quot;callback_next&quot;:&quot;&quot;,&quot;manage_history&quot;:&quot;enabled&quot;,&quot;has_controls_in_form&quot;:&quot;disabled&quot;,&quot;infinite_tolerance&quot;:&quot;0&quot;,&quot;max_pages&quot;:0,&quot;page&quot;:1,&quot;base_permalink&quot;:&quot;\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=12099&amp;wpv_paged=WPV_PAGE_NUM&quot;,&quot;loop&quot;:{&quot;type&quot;:&quot;&quot;,&quot;name&quot;:&quot;&quot;,&quot;data&quot;:[],&quot;id&quot;:0}}\" data-permalink=\"\/de\/wp-json\/wp\/v2\/pages\/5917?wpv_view_count=12099\">\n\n\t\n\t\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Welche Profile haben Ihre zertifizierten Experten?<\/h3>\n    <p>Wir arbeiten mit einer Vielzahl von Profilen aus der Technologiebranche zusammen. Hier einige Beispiele:<\/p>\n<ul>\n<li>Entwickler von Apps und Websites<\/li>\n<li>Software-Entwickler<\/li>\n<li>Experten f\u00fcr Design Thinking<\/li>\n<li>UX\/UI-Entwickler<\/li>\n<li>Grafik-Designer<\/li>\n<li>Digitale Vermarkter (SEO, ASO, SEM usw.)<\/li>\n<\/ul>\n<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wo kann ich mich als zertifizierter Experte bewerben?<\/h3>\n    <p>Wenn Sie unserer Plattform beitreten m\u00f6chten, k\u00f6nnen Sie sich <span class=\"ypOpenRegisterDeveloperModal\"><a href=\"https:\/\/yeeply.com\/de\/faq\/#publish-project\" rel=\"noopener noreferrer\" target=\"_blank\">hier<\/a><\/span> anmelden. Nachdem Sie das Formular ausgef\u00fcllt haben, erhalten Sie eine E-Mail mit Anweisungen zur Aktivierung Ihres Kontos. Sobald Sie die Plattform betreten haben, k\u00f6nnen Sie Ihr Profil vervollst\u00e4ndigen, indem Sie alle relevanten Informationen wie Ihre <strong>Fachkenntnisse, F\u00e4higkeiten und Erfahrungen<\/strong> hinzuf\u00fcgen.<\/p>\n<p>Nachdem Sie dies getan haben, m\u00fcssen Sie warten, bis wir Sie bez\u00fcglich der n\u00e4chsten Schritte kontaktieren. Diese k\u00f6nnen aus einem Vorstellungsgespr\u00e4ch, einer Referenzpr\u00fcfung, der \u00dcberpr\u00fcfung der technischen F\u00e4higkeiten usw. bestehen<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Wie lange wird es dauern, bis ich eine Antwort auf meine Bewerbung erhalte?<\/h3>\n    <p>Unsere Experten werden nach dem First-Come, First-Serve-Prinzip zertifiziert &#8211; je nach den Merkmalen ihres Profils und dem Gleichgewicht zwischen Angebot und Nachfrage.<\/p>\n<p>Wir haben eine lange Warteliste, und nur <strong>1% der Kandidaten bestehen unser Zertifizierungsverfahren<\/strong>. Wenn wir an Fachleuten mit Ihrem Profil interessiert sind und diese ben\u00f6tigen, werden wir uns mit Ihnen in Verbindung setzen, um die notwendigen Schritte einzuleiten.<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Was sind die Vorteile einer Zusammenarbeit mit Yeeply als zertifizierter Experte?<\/h3>\n    <p>Im Gegensatz zu anderen Plattformen erheben wir keine Provisionen oder Mitgliedsbeitr\u00e4ge. Weitere Vorteile sind:<\/p>\n<ul>\n<li>Sie sparen Marketingkosten, um neue Kunden zu gewinnen und neue Projekte zu unterzeichnen.<\/li>\n<li>Wir filtern die eingehenden Leads, um sicherzustellen, dass Sie sich nur auf qualitativ hochwertige Projekte konzentrieren, die Ihrem Fachwissen entsprechen.<\/li>\n<li>Es steht Ihnen frei, neue Projekte anzunehmen oder abzulehnen, und Sie k\u00f6nnen Ihre eigenen Preise festlegen.<\/li>\n<li>Sie k\u00f6nnen direkt mit dem Kunden kommunizieren, und es besteht volle Transparenz \u00fcber den Endpreis.<\/li>\n<\/ul>\n<\/p>\n<\/div>\n\t\n\t\t<div class=\"single-main-faq\">\n    <h3>Kann ich nach meiner Zertifizierung von der Plattform entfernt werden?<\/h3>\n    <p>Ja, das ist m\u00f6glich. Wir versuchen stets, die h\u00f6chsten Standards einzuhalten. In den folgenden F\u00e4llen k\u00f6nnten Sie von unserer Plattform entfernt werden:<\/p>\n<ul>\n<li>Nichteinhaltung der im Vertrag festgelegten Klauseln<\/li>\n<li>Eine pl\u00f6tzliche Abnahme der Qualit\u00e4t Ihrer Arbeit<\/li>\n<li>Falsche Behandlung von Kunden.<\/li>\n<li>usw.<\/li>\n<\/ul>\n<p>Wir versuchen jedoch immer, den Fall zu untersuchen, und je nach Schwere des Falles kann ein Experte vor\u00fcbergehend oder dauerhaft von einem Projekt und der Plattform ausgeschlossen werden.<\/p>\n<\/div>\n\t\n\t\n\t\n\t\n<\/div>\n<\/div>\n<\/div><\/div><\/section>\n\n\n\n<p class=\"has-text-align-center\"><strong>Fehlt eine Frage? Kontaktieren Sie uns \u00fcber info@yeeply.com und wir werden sie auf unserer Seite hinzuf\u00fcgen! ?<\/strong><\/p>\n<\/div><\/section>\n\n\n\n<div class=\"wp-block-cover aligncenter has-parallax is-light home-click-to-action\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\"><\/span><div class=\"wp-block-cover__image-background wp-image-5457 has-parallax\" style=\"background-position:50% 50%;background-image:url(https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_support.jpg)\"><\/div><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<h2 class=\"wp-block-heading has-text-align-center\">Sind Sie bereit f\u00fcr Ihr erstes Projekt?<\/h2>\n\n\n\n<div class=\"wp-block-button btn-blue ypOpenPublishProjectModal ga-cta-bottom aligncenter\"><a class=\"wp-block-button__link wp-element-button\" href=\"\">ICH M\u00d6CHTE EINE PREISSCH\u00c4TZUNG ERHALTEN<\/a><\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":35,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"_uag_custom_page_level_css":"","footnotes":""},"categories":[],"class_list":["post-5917","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FAQ - H\u00e4ufige Fragen - Yeeply<\/title>\n<meta name=\"description\" content=\"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/yeeply.com\/de\/faq\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FAQ - H\u00e4ufige Fragen - Yeeply\" \/>\n<meta property=\"og:description\" content=\"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/yeeply.com\/de\/faq\/\" \/>\n<meta property=\"og:site_name\" content=\"Yeeply\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/YeeplyMobile\/\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-12T10:34:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Yeeply_EN\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/\",\"url\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/\",\"name\":\"FAQ - H\u00e4ufige Fragen - Yeeply\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/yeeply.com\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/img_bg_faq@2x.jpg\",\"datePublished\":\"2024-07-12T10:34:44+00:00\",\"dateModified\":\"2024-07-12T10:34:49+00:00\",\"description\":\"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/#primaryimage\",\"url\":\"https:\\\/\\\/yeeply.com\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/img_bg_faq@2x.jpg\",\"contentUrl\":\"https:\\\/\\\/yeeply.com\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/img_bg_faq@2x.jpg\",\"width\":2880,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/faq\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/yeeply.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FAQ \u2013 H\u00e4ufige Fragen \u2013 Yeeply\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/yeeply.com\\\/de\\\/\",\"name\":\"Yeeply\",\"description\":\"A platform for the development of digital projects\",\"publisher\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/yeeply.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#organization\",\"name\":\"Yeeply\",\"url\":\"https:\\\/\\\/yeeply.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/yeeply.com\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_yeeply_black@2x.png\",\"contentUrl\":\"https:\\\/\\\/yeeply.com\\\/de\\\/wp-content\\\/uploads\\\/2019\\\/05\\\/logo_yeeply_black@2x.png\",\"width\":360,\"height\":120,\"caption\":\"Yeeply\"},\"image\":{\"@id\":\"https:\\\/\\\/yeeply.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/YeeplyMobile\\\/\",\"https:\\\/\\\/x.com\\\/Yeeply_EN\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/yeeply\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FAQ - H\u00e4ufige Fragen - Yeeply","description":"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/yeeply.com\/de\/faq\/","og_locale":"de_DE","og_type":"article","og_title":"FAQ - H\u00e4ufige Fragen - Yeeply","og_description":"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.","og_url":"https:\/\/yeeply.com\/de\/faq\/","og_site_name":"Yeeply","article_publisher":"https:\/\/www.facebook.com\/YeeplyMobile\/","article_modified_time":"2024-07-12T10:34:49+00:00","og_image":[{"url":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Yeeply_EN","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/yeeply.com\/de\/faq\/","url":"https:\/\/yeeply.com\/de\/faq\/","name":"FAQ - H\u00e4ufige Fragen - Yeeply","isPartOf":{"@id":"https:\/\/yeeply.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/yeeply.com\/de\/faq\/#primaryimage"},"image":{"@id":"https:\/\/yeeply.com\/de\/faq\/#primaryimage"},"thumbnailUrl":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg","datePublished":"2024-07-12T10:34:44+00:00","dateModified":"2024-07-12T10:34:49+00:00","description":"Hier sind einige der am h\u00e4ufigsten gestellten Fragen, die wir bei Yeeply erhalten. Schauen Sie die Fragen durch und finden Sie die richtige Antwort.","breadcrumb":{"@id":"https:\/\/yeeply.com\/de\/faq\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/yeeply.com\/de\/faq\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yeeply.com\/de\/faq\/#primaryimage","url":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg","contentUrl":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/img_bg_faq@2x.jpg","width":2880,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/yeeply.com\/de\/faq\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/yeeply.com\/de\/"},{"@type":"ListItem","position":2,"name":"FAQ \u2013 H\u00e4ufige Fragen \u2013 Yeeply"}]},{"@type":"WebSite","@id":"https:\/\/yeeply.com\/de\/#website","url":"https:\/\/yeeply.com\/de\/","name":"Yeeply","description":"A platform for the development of digital projects","publisher":{"@id":"https:\/\/yeeply.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/yeeply.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/yeeply.com\/de\/#organization","name":"Yeeply","url":"https:\/\/yeeply.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/yeeply.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/logo_yeeply_black@2x.png","contentUrl":"https:\/\/yeeply.com\/de\/wp-content\/uploads\/2019\/05\/logo_yeeply_black@2x.png","width":360,"height":120,"caption":"Yeeply"},"image":{"@id":"https:\/\/yeeply.com\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/YeeplyMobile\/","https:\/\/x.com\/Yeeply_EN","https:\/\/www.linkedin.com\/company\/yeeply"]}]}},"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"gform-image-choice-sm":false,"gform-image-choice-md":false,"gform-image-choice-lg":false},"uagb_author_info":{"display_name":"Yolanda P\u00e9rez","author_link":"https:\/\/yeeply.com\/de\/author\/yolanda-perez\/"},"uagb_comment_info":0,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/pages\/5917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/comments?post=5917"}],"version-history":[{"count":0,"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/pages\/5917\/revisions"}],"wp:attachment":[{"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/media?parent=5917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yeeply.com\/de\/wp-json\/wp\/v2\/categories?post=5917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}